{"id":26,"count":12,"description":"Wir als voestalpine bieten zahlreiche Berufsm\u00f6glichkeiten und Karrierechancen und arbeiten unaufh\u00f6rlich daran, unseren Mitarbeiter:innen eine attraktive Arbeitswelt zu bieten. Zentrales Fundament ist eine wertsch\u00e4tzende Unternehmenskultur.","link":"https:\/\/www.voestalpine.com\/blog\/de\/karriere\/arbeitswelten\/","name":"Arbeitswelten","slug":"arbeitswelten","taxonomy":"category","parent":96,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arbeitswelten Archive - voestalpine Corporate Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.voestalpine.com\/blog\/de\/karriere\/arbeitswelten\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arbeitswelten Archive - voestalpine Corporate Blog\" \/>\n<meta property=\"og:description\" content=\"Wir als voestalpine bieten zahlreiche Berufsm\u00f6glichkeiten und Karrierechancen und arbeiten unaufh\u00f6rlich daran, unseren Mitarbeiter:innen eine attraktive Arbeitswelt zu bieten. Zentrales Fundament ist eine wertsch\u00e4tzende Unternehmenskultur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.voestalpine.com\/blog\/de\/karriere\/arbeitswelten\/\" \/>\n<meta property=\"og:site_name\" content=\"voestalpine Corporate Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arbeitswelten Archive - voestalpine Corporate Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.voestalpine.com\/blog\/de\/karriere\/arbeitswelten\/","og_locale":"en_US","og_type":"article","og_title":"Arbeitswelten Archive - voestalpine Corporate Blog","og_description":"Wir als voestalpine bieten zahlreiche Berufsm\u00f6glichkeiten und Karrierechancen und arbeiten unaufh\u00f6rlich daran, unseren Mitarbeiter:innen eine attraktive Arbeitswelt zu bieten. Zentrales Fundament ist eine wertsch\u00e4tzende Unternehmenskultur.","og_url":"https:\/\/www.voestalpine.com\/blog\/de\/karriere\/arbeitswelten\/","og_site_name":"voestalpine Corporate Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.voestalpine.com\/blog\/de\/karriere\/arbeitswelten\/","url":"https:\/\/www.voestalpine.com\/blog\/de\/karriere\/arbeitswelten\/","name":"Arbeitswelten Archive - voestalpine Corporate Blog","isPartOf":{"@id":"https:\/\/www.voestalpine.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.voestalpine.com\/blog\/de\/karriere\/arbeitswelten\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.voestalpine.com\/blog\/de\/karriere\/arbeitswelten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.voestalpine.com\/blog\/de\/"},{"@type":"ListItem","position":2,"name":"Karriere","item":"https:\/\/www.voestalpine.com\/blog\/de\/karriere\/"},{"@type":"ListItem","position":3,"name":"Arbeitswelten"}]},{"@type":"WebSite","@id":"https:\/\/www.voestalpine.com\/blog\/#website","url":"https:\/\/www.voestalpine.com\/blog\/","name":"voestalpine Corporate Blog","description":"","publisher":{"@id":"https:\/\/www.voestalpine.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.voestalpine.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.voestalpine.com\/blog\/#organization","name":"voestalpine Corporate Blog","url":"https:\/\/www.voestalpine.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.voestalpine.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.voestalpine.com\/blog\/wp-content\/uploads\/2023\/10\/logo_voestalpine_header.svg","contentUrl":"https:\/\/www.voestalpine.com\/blog\/wp-content\/uploads\/2023\/10\/logo_voestalpine_header.svg","width":240,"height":50,"caption":"voestalpine Corporate Blog"},"image":{"@id":"https:\/\/www.voestalpine.com\/blog\/#\/schema\/logo\/image\/"}}]}},"lang":"de","translations":{"de":26,"en":76},"_links":{"self":[{"href":"https:\/\/www.voestalpine.com\/blog\/wp-json\/wp\/v2\/categories\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.voestalpine.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.voestalpine.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.voestalpine.com\/blog\/wp-json\/wp\/v2\/categories\/96"}],"wp:post_type":[{"href":"https:\/\/www.voestalpine.com\/blog\/wp-json\/wp\/v2\/posts?categories=26"},{"href":"https:\/\/www.voestalpine.com\/blog\/wp-json\/wp\/v2\/news?categories=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}