{"id":145,"date":"2018-10-04T16:21:08","date_gmt":"2018-10-04T14:21:08","guid":{"rendered":"https:\/\/voest.5q.at\/bestelehresteiermark\/elektrotechnik\/"},"modified":"2026-01-21T10:08:19","modified_gmt":"2026-01-21T09:08:19","slug":"elektrotechnik-anlagen-und-betriebstechnik","status":"publish","type":"page","link":"https:\/\/www.voestalpine.com\/bestelehresteiermark\/ausbildungen\/elektrotechnik-anlagen-und-betriebstechnik\/","title":{"rendered":"Elektrotechnik \u2013 Anlagen- und Betriebstechnik"},"content":{"rendered":"\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.voestalpine.com\/bestelehresteiermark\/wp-content\/uploads\/2024\/08\/7-elektrotechnik-anlagen-und-betriebstechnik-header.jpg\" alt=\"7_Elektrotechnik_Anlagen-und_Betriebstechnik_Header\" itemprop=\"image\" height=\"950\" width=\"2340\" title=\"7_Elektrotechnik_Anlagen-und_Betriebstechnik_Header\" onerror=\"this.style.display='none'\"  \/>\n\t<h2>Lehre Elektrotechnik \/ Anlagen- und Betriebstechnik<\/h2>\n\t<p><img loading=\"lazy\" decoding=\"async\" src=\"..\/..\/wp-content\/uploads\/2018\/10\/Icons_lehrzeit-150x150.png\" alt=\"Lehrzeit\" width=\"100\" height=\"89\" \/><\/p>\n\t<p>Lehrzeit: 3,5 Jahre<\/p>\n\t<p>Mit ausreichend Coolness bist du Feuerwehr bei St\u00f6rf\u00e4llen in der Produktion und beweist detektivischen Spu\u0308rsinn bei mess- und regeltechnischen Abweichungen. Dein Job ist es, eine sichere Energieversorgung zu gew\u00e4hrleisten und fu\u0308r den reibungslosen Betrieb voll automatisierter Anlagen zu sorgen.<\/p>\n<p>Elektrotechniker\/-innen planen, montieren, installieren, warten und reparieren verschiedenste elektrische und elektronische Ger\u00e4te und Anlagen wie z. B. Steuerungs- und Regelungsanlagen, Alarmsysteme, \u00dcberwachungssysteme, elektrische Tu\u0308ren und Tore, elektrische Geb\u00e4udeinstallationen (Stromleitungen) und industrielle Maschinen.<\/p>\n\t<h2>Spezialisierungen<\/h2>\n<ul>\n<li>Elektro- und Geb\u00e4udetechnik<\/li>\n<li>Energietechnik<\/li>\n<li>Anlagen- und Betriebstechnik<\/li>\n<li>Automatisierungs- und Prozessleittechnik<\/li>\n<\/ul>\n\t\t<h3><\/h3>\t\t\n\t\t\t<p>&nbsp;<\/p>\n<p>&#8220;Die Fehlersuche ist ein wesentlicher Teil meiner Arbeit. Wichtig dabei ist es logisch zu denken und die Anlage zu verstehen. Vor allem das Plan lesen war f\u00fcr mich am Anfang sehr schwierig, aber mittlerweile funktioniert das auch schon sehr gut&#8221;<\/p>\n<p><em>&#8211; Matthias Oberer, voestalpine Tubulars GmbH &amp; Co KG<\/em><\/p>\n\t<strong>Deine F\u00e4higkeiten<br \/>\n<\/strong>Motivation &amp; Lernbereitschaft, vernetztes Denken &amp; geistige Beweglichkeit, Pr\u00e4zision<br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"..\/..\/wp-content\/uploads\/2018\/10\/Icons_faehigkeiten_ohnentext_motivation_lernbereitschaft.png\" alt=\"Motivation und Lernbereitschaft\" width=\"100\" height=\"89\" \/><img loading=\"lazy\" decoding=\"async\" src=\"..\/..\/wp-content\/uploads\/2018\/10\/Icons_faehigkeiten_ohnentext_vernetztesdenken.png\" alt=\"vernetztes Denken\" width=\"100\" height=\"89\" \/><img loading=\"lazy\" decoding=\"async\" src=\"..\/..\/wp-content\/uploads\/2018\/10\/Icons_faehigkeiten_ohnentext_praezision.png\" alt=\"Praezision\" width=\"100\" height=\"89\" \/>\n\t<h2>Dein Einkommen<\/h2>\n<ul>\n<li>1. Lehrjahr: 1.071,00 \u20ac<\/li>\n<li>2. Lehrjahr: 1.295,40 \u20ac<\/li>\n<li>3. Lehrjahr: 1.657,50 \u20ac<\/li>\n<li>4. Lehrjahr: 2.152,20 \u20ac<\/li>\n<\/ul>\n\t<p><a href=\"#\"> Download Factsheet<\/a>\u00a0(<em>Verlinkung folgt)<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"\/bestelehresteiermark\/wp-content\/uploads\/2018\/10\/Steiermarkkarte_Standort_Bruckandermur.png\" alt=\"\" width=\"463\" height=\"319\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"\/bestelehresteiermark\/wp-content\/uploads\/2018\/10\/Steiermarkkarte_Standort_Kapfenberg.png\" alt=\"\" width=\"463\" height=\"319\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"\/bestelehresteiermark\/wp-content\/uploads\/2018\/10\/Steiermarkkarte_Standort_Kindberg.png\" alt=\"\" width=\"463\" height=\"319\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"\/bestelehresteiermark\/wp-content\/uploads\/2018\/10\/Steiermarkkarte_Standort_Krieglach.png\" alt=\"\" width=\"463\" height=\"319\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.voestalpine.com\/bestelehresteiermark\/wp-content\/uploads\/2024\/09\/steiermarkkarte-standort-leoben-donawitz-1.png\" alt=\"\" width=\"463\" height=\"319\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"\/bestelehresteiermark\/wp-content\/uploads\/2018\/10\/Steiermarkkarte_Standort_Muerzzuschlag.png\" alt=\"\" width=\"463\" height=\"319\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"\/bestelehresteiermark\/wp-content\/uploads\/2018\/10\/Steiermarkkarte_Standort_stpeterfreienstein.png\" alt=\"\" width=\"463\" height=\"319\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"\/bestelehresteiermark\/wp-content\/uploads\/2018\/10\/Steiermarkkarte_Standort_Zeltweg.png\" alt=\"\" width=\"463\" height=\"319\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"\/bestelehresteiermark\/wp-content\/uploads\/2018\/10\/Steiermarkkarte_Standort.png\" alt=\"\" width=\"463\" height=\"319\" \/><\/p>\n\t<iframe loading=\"lazy\" width=\"321\" height=\"576\" src=\"https:\/\/www.youtube.com\/embed\/96UM0aiB6sA\" title=\"voestalpine Lehre Elektrotechnik\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n\t<h2>Ausbildungsorte:<\/h2>\n<p>&nbsp;<\/p>\n\tBruck an der Mur \/ voestalpine Wire Austria GmbH<br \/>\n<a href=\"https:\/\/jobs.voestalpine.com\/index.php?ac=jobad&amp;id=19341\">Zur Stellenanzeige im Jobportal<\/a>\nKapfenberg \/ voestalpine B\u00f6hler Welding Austria GmbH<br \/>\n<a href=\"https:\/\/jobs.voestalpine.com\/index.php?ac=jobad&amp;id=19195\">Zur Stellenanzeige im Jobportal<\/a>\nKindberg \/ voestalpine Tubulars GmbH &amp; Co KG<br \/>\n<a href=\"https:\/\/jobs.voestalpine.com\/index.php?ac=jobad&amp;id=19324\">Zur Stellenanzeige im Jobportal<\/a>\n\t\t<h3><\/h3>\t\t\n\t\t\t<strong> Du interessierst dich f\u00fcr diese Ausbildung und m\u00f6chtest dich bewerben?<br \/>\n<\/strong>Die Checkliste hilft dir, dich bestm\u00f6glich vorzubereiten.<br \/>\n <a href=\"https:\/\/www.voestalpine.com\/bestelehresteiermark\/#checkliste\">Checkliste<\/a>\n\t<h3>Hast du eine Frage zu diesem Lehrberuf?<\/h3>\n<p>Wir helfen dir gerne weiter.<\/p>\n\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f969-o1\" lang=\"de-DE\" dir=\"ltr\" data-wpcf7-id=\"969\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/bestelehresteiermark\/wp-json\/wp\/v2\/pages\/145#wpcf7-f969-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Kontaktformular\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"969\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"de_DE\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f969-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p>Ich m\u00f6chte mehr wissen \u00fcber den Lehrberuf: <span style=\"font-weight:400;\">Elektrotechnik \u2013 Anlagen- und Betriebstechnik<\/span>\n<\/p>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-standort\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-standort\"><option value=\"\">Standort w\u00e4hlen<\/option><option value=\"Bruck an der Mur \/ voestalpine Wire Austria GmbH\">Bruck an der Mur \/ voestalpine Wire Austria GmbH<\/option><option value=\"Kapfenberg \/ voestalpine B\u00f6hler Welding Austria GmbH\">Kapfenberg \/ voestalpine B\u00f6hler Welding Austria GmbH<\/option><option value=\"Kindberg \/ voestalpine Tubulars GmbH &amp; Co KG\">Kindberg \/ voestalpine Tubulars GmbH &amp; Co KG<\/option><\/select><\/span><\/label>\n<\/p>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Vorname Nachname\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Meine E-Mail\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Meine Telefonnummer\" value=\"\" type=\"tel\" name=\"your-tel\" \/><\/span> <\/label>\n<\/p>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Meine Frage\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"quiz-113\"><label><span class=\"wpcf7-quiz-label\">Wieviel ist 2 + 8<\/span> <input size=\"40\" class=\"wpcf7-form-control wpcf7-quiz\" autocomplete=\"off\" aria-required=\"true\" aria-invalid=\"false\" type=\"text\" name=\"quiz-113\" \/><\/label><input type=\"hidden\" name=\"_wpcf7_quiz_answer_quiz-113\" value=\"a582ac202470fbb15ac42aa9d1d65a60\" \/><\/span><\/label>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-20\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-20\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\"><span class=\"datenschutzlink\">Ich akzeptiere die <a  href=\"https:\/\/www.voestalpine.com\/bestelehresteiermark\/datenschutz\/\" target=\"_blank\" title=\"Datenschutzbedingungen\">Datenschutzbedingungen<\/a><\/span><\/span><\/label><\/span><\/span><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Absenden\" \/><input type=\"reset\" class='button btn btn-primary' \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n\t<p>Perfekter Job f\u00fcr deine\/n Freund\/-in?<\/p>\n<p><strong>Ausbildung verschicken<\/strong><\/p>\n<div class=\"addtoany_shortcode\"><div class=\"a2a_kit a2a_kit_size_32 addtoany_list\" data-a2a-url=\"https:\/\/www.voestalpine.com\/bestelehresteiermark\/ausbildungen\/elektrotechnik-anlagen-und-betriebstechnik\/\" data-a2a-title=\"Elektrotechnik \u2013 Anlagen- und Betriebstechnik\"><a class=\"a2a_button_facebook\" href=\"https:\/\/www.addtoany.com\/add_to\/facebook?linkurl=https%3A%2F%2Fwww.voestalpine.com%2Fbestelehresteiermark%2Fausbildungen%2Felektrotechnik-anlagen-und-betriebstechnik%2F&amp;linkname=Elektrotechnik%20%E2%80%93%20Anlagen-%20und%20Betriebstechnik\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><a class=\"a2a_button_twitter\" href=\"https:\/\/www.addtoany.com\/add_to\/twitter?linkurl=https%3A%2F%2Fwww.voestalpine.com%2Fbestelehresteiermark%2Fausbildungen%2Felektrotechnik-anlagen-und-betriebstechnik%2F&amp;linkname=Elektrotechnik%20%E2%80%93%20Anlagen-%20und%20Betriebstechnik\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><a class=\"a2a_button_pinterest\" href=\"https:\/\/www.addtoany.com\/add_to\/pinterest?linkurl=https%3A%2F%2Fwww.voestalpine.com%2Fbestelehresteiermark%2Fausbildungen%2Felektrotechnik-anlagen-und-betriebstechnik%2F&amp;linkname=Elektrotechnik%20%E2%80%93%20Anlagen-%20und%20Betriebstechnik\" title=\"Pinterest\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><a class=\"a2a_button_whatsapp\" href=\"https:\/\/www.addtoany.com\/add_to\/whatsapp?linkurl=https%3A%2F%2Fwww.voestalpine.com%2Fbestelehresteiermark%2Fausbildungen%2Felektrotechnik-anlagen-und-betriebstechnik%2F&amp;linkname=Elektrotechnik%20%E2%80%93%20Anlagen-%20und%20Betriebstechnik\" title=\"WhatsApp\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><a class=\"a2a_button_email\" href=\"https:\/\/www.addtoany.com\/add_to\/email?linkurl=https%3A%2F%2Fwww.voestalpine.com%2Fbestelehresteiermark%2Fausbildungen%2Felektrotechnik-anlagen-und-betriebstechnik%2F&amp;linkname=Elektrotechnik%20%E2%80%93%20Anlagen-%20und%20Betriebstechnik\" title=\"Email\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Lehre Elektrotechnik \/ Anlagen- und Betriebstechnik Lehrzeit: 3,5 Jahre Mit ausreichend Coolness bist du Feuerwehr bei St\u00f6rf\u00e4llen in der Produktion und beweist detektivischen Spu\u0308rsinn bei mess- und regeltechnischen Abweichungen. Dein Job ist es, eine sichere Energieversorgung zu gew\u00e4hrleisten und fu\u0308r den reibungslosen Betrieb voll automatisierter Anlagen zu sorgen. Elektrotechniker\/-innen planen, montieren, installieren, warten und reparieren verschiedenste elektrische und elektronische Ger\u00e4te und Anlagen wie z. B. &hellip; <a href=\"https:\/\/www.voestalpine.com\/bestelehresteiermark\/ausbildungen\/elektrotechnik-anlagen-und-betriebstechnik\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Elektrotechnik \u2013 Anlagen- und Betriebstechnik<\/span> <span class=\"meta-nav\">&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":8,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/full-width.php","meta":{"footnotes":""},"class_list":["post-145","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.voestalpine.com\/bestelehresteiermark\/wp-json\/wp\/v2\/pages\/145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.voestalpine.com\/bestelehresteiermark\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.voestalpine.com\/bestelehresteiermark\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.voestalpine.com\/bestelehresteiermark\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.voestalpine.com\/bestelehresteiermark\/wp-json\/wp\/v2\/comments?post=145"}],"version-history":[{"count":123,"href":"https:\/\/www.voestalpine.com\/bestelehresteiermark\/wp-json\/wp\/v2\/pages\/145\/revisions"}],"predecessor-version":[{"id":5477,"href":"https:\/\/www.voestalpine.com\/bestelehresteiermark\/wp-json\/wp\/v2\/pages\/145\/revisions\/5477"}],"up":[{"embeddable":true,"href":"https:\/\/www.voestalpine.com\/bestelehresteiermark\/wp-json\/wp\/v2\/pages\/8"}],"wp:attachment":[{"href":"https:\/\/www.voestalpine.com\/bestelehresteiermark\/wp-json\/wp\/v2\/media?parent=145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}